{"id":17783,"date":"2024-05-17T06:30:59","date_gmt":"2024-05-17T06:30:59","guid":{"rendered":"https:\/\/agenciameridianos.com\/web\/?page_id=17783"},"modified":"2024-12-05T22:55:24","modified_gmt":"2024-12-05T22:55:24","slug":"conoce-nuestras-playas","status":"publish","type":"page","link":"https:\/\/agenciameridianos.com\/en\/conoce-nuestras-playas\/","title":{"rendered":"Conoc\u00e9 Nuestras Playas"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"17783\" class=\"elementor elementor-17783\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12153be e-con-full e-flex e-con e-parent\" data-id=\"12153be\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dd08e72 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"dd08e72\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-b4833ad swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Vista panor\u00e1mica de playas paradis\u00edacas en Costa Rica al atardecer\"><\/div><div class=\"elementor-background-overlay\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7448994 e-flex e-con-boxed e-con e-parent\" data-id=\"7448994\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7aa9806 elementor-widget elementor-widget-spacer\" data-id=\"7aa9806\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5ada97d e-con-full e-flex e-con e-child\" data-id=\"5ada97d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b4dcf32 elementor-widget elementor-widget-button\" data-id=\"b4dcf32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/agenciameridianos.com\/en\/conoce-nuestras-playas\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Beaches<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-000399d elementor-widget elementor-widget-button\" data-id=\"000399d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/agenciameridianos.com\/en\/conoce-nuestras-montanas\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mountain<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2611aee elementor-widget elementor-widget-button\" data-id=\"2611aee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/agenciameridianos.com\/en\/one-day-tour\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">One day tour<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e0cf56 e-flex e-con-boxed e-con e-parent\" data-id=\"6e0cf56\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-222b95a elementor-product-loop-item--align-center elementor-grid-4 elementor-grid-tablet-3 elementor-grid-mobile-2 elementor-products-grid elementor-wc-products elementor-widget elementor-widget-woocommerce-products\" data-id=\"222b95a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woocommerce-products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"woocommerce columns-4\"><div class=\"woocommerce-notices-wrapper\"><\/div><ul class=\"products elementor-grid columns-4\">\n<li class=\"product type-product post-21915 status-publish first instock product_cat-conoce-costa-rica product_cat-one-day product_cat-playa product_cat-todos-los-paquetes product_tag-desde has-post-thumbnail featured shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/agenciameridianos.com\/en\/product\/catamaranypuntaeternia\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/09\/eternia-5-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Imagen de naves espaciales sobrevolando la galaxia Eternia\" srcset=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/09\/eternia-5-300x300.jpg 300w, https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/09\/eternia-5-150x150.jpg 150w, https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/09\/eternia-5-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><h2 class=\"woocommerce-loop-product__title\">La Raya and Punta Eternia Catamaran<\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">USD $<\/span>159<\/bdi><\/span><\/span>\n <div class=\"cg-amenities\" style=\"font-family: 'Montserrat', sans-serif; color: black; text-transform: capitalize;\"><\/div>\r\n    <div class=\"cg-amenities\">                                <img decoding=\"async\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/05\/Transport-icon.svg\" title=\"transporte\" style=\"width:40px; display: inline-block; margin: 0; padding: 0;\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/05\/Foods-Icon.svg\" title=\"alimentos\" style=\"width:40px; display: inline-block; margin: 0; padding: 0;\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/05\/Tickets-Icon.svg\" title=\"entradas\" style=\"width:40px; display: inline-block; margin: 0; padding: 0;\">\r\n                        <\/div>\r\n    <\/a><div class=\"woocommerce-loop-product__buttons\"><a class=\"button wpt-custom-view-product-button\" href=\"https:\/\/agenciameridianos.com\/en\/product\/catamaranypuntaeternia\/\" data-no-translation=\"\" data-trp-gettext=\"\">Quote<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_21915\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/li>\n<li class=\"product type-product post-21912 status-publish instock product_cat-conoce-costa-rica product_cat-playa product_cat-todos-los-paquetes product_tag-desde has-post-thumbnail featured shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/agenciameridianos.com\/en\/product\/comprasengolfito\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/09\/Compras-Golfito-3-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Centro de Compras en Golfito con Oportunidades \u00danicas\" srcset=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/09\/Compras-Golfito-3-300x300.jpg 300w, https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/09\/Compras-Golfito-3-150x150.jpg 150w, https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/09\/Compras-Golfito-3-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><h2 class=\"woocommerce-loop-product__title\">Shopping in Golfito<\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">USD $<\/span>129<\/bdi><\/span><\/span>\n <div class=\"cg-amenities\" style=\"font-family: 'Montserrat', sans-serif; color: black; text-transform: capitalize;\"><\/div>\r\n    <div class=\"cg-amenities\">                                <img decoding=\"async\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/05\/Transport-icon.svg\" title=\"transporte\" style=\"width:40px; display: inline-block; margin: 0; padding: 0;\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/05\/Tours-Icon.svg\" title=\"tours\" style=\"width:40px; display: inline-block; margin: 0; padding: 0;\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/05\/Lodging-Icon.svg\" title=\"hospedaje\" style=\"width:40px; display: inline-block; margin: 0; padding: 0;\">\r\n                        <\/div>\r\n    <\/a><div class=\"woocommerce-loop-product__buttons\"><a href=\"\/en\/wp-json\/wp\/v2\/pages\/17783?add-to-cart=21912\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_21912\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"21912\" data-product_sku=\"\" aria-label=\"Add to cart\" rel=\"nofollow\" data-success_message=\"\u201cCompras en Golfito\u201d has been added to your cart\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\">Add to cart<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_21912\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/li>\n<li class=\"product type-product post-21503 status-publish instock product_cat-conoce-costa-rica product_cat-montana product_cat-playa product_cat-todos-los-paquetes product_tag-desde has-post-thumbnail featured shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/agenciameridianos.com\/en\/product\/costaricaescenica\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/09\/costarica-escenica-agencia-meridianos289602853-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Costa Rica Esc\u00e9nica\" srcset=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/09\/costarica-escenica-agencia-meridianos289602853-300x300.jpg 300w, https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/09\/costarica-escenica-agencia-meridianos289602853-150x150.jpg 150w, https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/09\/costarica-escenica-agencia-meridianos289602853-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><h2 class=\"woocommerce-loop-product__title\">Costa Rica Scenic<\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">USD $<\/span>1,995<\/bdi><\/span><\/span>\n <div class=\"cg-amenities\" style=\"font-family: 'Montserrat', sans-serif; color: black; text-transform: capitalize;\"><\/div>\r\n    <div class=\"cg-amenities\">                                <img decoding=\"async\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/05\/Transport-icon.svg\" title=\"transporte\" style=\"width:40px; display: inline-block; margin: 0; padding: 0;\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/05\/Tours-Icon.svg\" title=\"tours\" style=\"width:40px; display: inline-block; margin: 0; padding: 0;\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/05\/Breakfast2-Icon.svg\" title=\"desayunos\" style=\"width:40px; display: inline-block; margin: 0; padding: 0;\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/05\/Lodging-Icon.svg\" title=\"hospedaje\" style=\"width:40px; display: inline-block; margin: 0; padding: 0;\">\r\n                        <\/div>\r\n    <\/a><div class=\"woocommerce-loop-product__buttons\"><a href=\"\/en\/wp-json\/wp\/v2\/pages\/17783?add-to-cart=21503\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_21503\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"21503\" data-product_sku=\"\" aria-label=\"Add to cart\" rel=\"nofollow\" data-success_message=\"\u201cCosta Rica Esc\u00e9nica\u201d has been added to your cart\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\">Add to cart<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_21503\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/li>\n<li class=\"product type-product post-21500 status-publish last instock product_cat-conoce-costa-rica product_cat-montana product_cat-playa product_cat-todos-los-paquetes product_tag-desde has-post-thumbnail featured shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/agenciameridianos.com\/en\/product\/costaricapuravida\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/09\/Puravida-costarica-agencia-meridianos780025775-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Vista panor\u00e1mica de Costa Rica promovida por Agencia Meridianos\" srcset=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/09\/Puravida-costarica-agencia-meridianos780025775-300x300.jpg 300w, https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/09\/Puravida-costarica-agencia-meridianos780025775-150x150.jpg 150w, https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/09\/Puravida-costarica-agencia-meridianos780025775-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><h2 class=\"woocommerce-loop-product__title\">Costa Rica Pura Vida<\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">USD $<\/span>999<\/bdi><\/span><\/span>\n <div class=\"cg-amenities\" style=\"font-family: 'Montserrat', sans-serif; color: black; text-transform: capitalize;\"><\/div>\r\n    <div class=\"cg-amenities\">                                <img decoding=\"async\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/05\/Transport-icon.svg\" title=\"transporte\" style=\"width:40px; display: inline-block; margin: 0; padding: 0;\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/05\/Tours-Icon.svg\" title=\"tours\" style=\"width:40px; display: inline-block; margin: 0; padding: 0;\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/05\/Breakfast2-Icon.svg\" title=\"desayunos\" style=\"width:40px; display: inline-block; margin: 0; padding: 0;\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/05\/Lodging-Icon.svg\" title=\"hospedaje\" style=\"width:40px; display: inline-block; margin: 0; padding: 0;\">\r\n                        <\/div>\r\n    <\/a><div class=\"woocommerce-loop-product__buttons\"><a href=\"\/en\/wp-json\/wp\/v2\/pages\/17783?add-to-cart=21500\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_21500\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"21500\" data-product_sku=\"\" aria-label=\"Add to cart\" rel=\"nofollow\" data-success_message=\"\u201cCosta Rica Pura Vida\u201d has been added to your cart\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\">Add to cart<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_21500\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/li>\n<li class=\"product type-product post-21510 status-publish first instock product_cat-conoce-costa-rica product_cat-montana product_cat-playa product_cat-todos-los-paquetes product_tag-desde has-post-thumbnail featured shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/agenciameridianos.com\/en\/product\/costaricaverde\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/09\/costarica-verde168243431-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Vista Panor\u00e1mica de la Naturaleza Verde en Costa Rica\" srcset=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/09\/costarica-verde168243431-300x300.jpg 300w, https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/09\/costarica-verde168243431-150x150.jpg 150w, https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/09\/costarica-verde168243431-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><h2 class=\"woocommerce-loop-product__title\">Green Costa Rica<\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">USD $<\/span>2,015<\/bdi><\/span><\/span>\n <div class=\"cg-amenities\" style=\"font-family: 'Montserrat', sans-serif; color: black; text-transform: capitalize;\"><\/div>\r\n    <div class=\"cg-amenities\">                                <img decoding=\"async\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/05\/Transport-icon.svg\" title=\"transporte\" style=\"width:40px; display: inline-block; margin: 0; padding: 0;\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/05\/Tours-Icon.svg\" title=\"tours\" style=\"width:40px; display: inline-block; margin: 0; padding: 0;\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/05\/Breakfast2-Icon.svg\" title=\"desayunos\" style=\"width:40px; display: inline-block; margin: 0; padding: 0;\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/05\/Lodging-Icon.svg\" title=\"hospedaje\" style=\"width:40px; display: inline-block; margin: 0; padding: 0;\">\r\n                        <\/div>\r\n    <\/a><div class=\"woocommerce-loop-product__buttons\"><a href=\"\/en\/wp-json\/wp\/v2\/pages\/17783?add-to-cart=21510\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_21510\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"21510\" data-product_sku=\"\" aria-label=\"Add to cart\" rel=\"nofollow\" data-success_message=\"\u201cCosta Rica Verde\u201d has been added to your cart\" data-no-translation=\"\" data-trp-gettext=\"\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\">Add to cart<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_21510\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/li>\n<li class=\"product type-product post-17170 status-publish instock product_cat-conoce-costa-rica product_cat-cotizar product_cat-playa product_cat-todos-los-paquetes product_tag-desde has-post-thumbnail shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/agenciameridianos.com\/en\/product\/dreams-las-mareas\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/05\/Dreams-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Representaci\u00f3n visual de sue\u00f1os e inspiraci\u00f3n\" \/><h2 class=\"woocommerce-loop-product__title\">Dreams las Mareas<\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">USD $<\/span>199<\/bdi><\/span><\/span>\n <div class=\"cg-amenities\" style=\"font-family: 'Montserrat', sans-serif; color: black; text-transform: capitalize;\"><\/div>\r\n    <div class=\"cg-amenities\">                                <img decoding=\"async\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/05\/Allinclusive.svg\" title=\"todo\" style=\"width:40px; display: inline-block; margin: 0; padding: 0;\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/05\/Lodging-Icon.svg\" title=\"hospedaje\" style=\"width:40px; display: inline-block; margin: 0; padding: 0;\">\r\n                        <\/div>\r\n    <\/a><div class=\"woocommerce-loop-product__buttons\"><a class=\"button wpt-custom-view-product-button\" href=\"https:\/\/agenciameridianos.com\/en\/product\/dreams-las-mareas\/\" data-no-translation=\"\" data-trp-gettext=\"\">Quote<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_17170\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/li>\n<li class=\"product type-product post-22989 status-publish instock product_cat-conoce-costa-rica product_cat-conoce-el-mundo product_cat-cotizar product_cat-playa product_cat-todos-los-paquetes product_tag-desde has-post-thumbnail featured shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/agenciameridianos.com\/en\/product\/fiesta-resort\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/11\/fiesta-puntarenas-3-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Personas disfrutando de una colorida fiesta en Puntarenas, Costa Rica\" srcset=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/11\/fiesta-puntarenas-3-300x300.jpg 300w, https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/11\/fiesta-puntarenas-3-150x150.jpg 150w, https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/11\/fiesta-puntarenas-3-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><h2 class=\"woocommerce-loop-product__title\">Fiesta Resort<\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">USD $<\/span>150<\/bdi><\/span><\/span>\n <div class=\"cg-amenities\" style=\"font-family: 'Montserrat', sans-serif; color: black; text-transform: capitalize;\"><\/div>\r\n    <div class=\"cg-amenities\">                                <img decoding=\"async\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/05\/Allinclusive.svg\" title=\"todo\" style=\"width:40px; display: inline-block; margin: 0; padding: 0;\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/05\/Foods-Icon.svg\" title=\"alimentos\" style=\"width:40px; display: inline-block; margin: 0; padding: 0;\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/05\/Lodging-Icon.svg\" title=\"hospedaje\" style=\"width:40px; display: inline-block; margin: 0; padding: 0;\">\r\n                        <\/div>\r\n    <\/a><div class=\"woocommerce-loop-product__buttons\"><a class=\"button wpt-custom-view-product-button\" href=\"https:\/\/agenciameridianos.com\/en\/product\/fiesta-resort\/\" data-no-translation=\"\" data-trp-gettext=\"\">Quote<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_22989\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/li>\n<li class=\"product type-product post-17199 status-publish last instock product_cat-conoce-costa-rica product_cat-cotizar product_cat-playa product_cat-todos-los-paquetes product_tag-desde has-post-thumbnail shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/agenciameridianos.com\/en\/product\/hospedaje-en-riu-guanacaste\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/05\/rui-guanacaste-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Vista del Hotel Riu Guanacaste con la Playa y el Oc\u00e9ano Pac\u00edfico\" \/><h2 class=\"woocommerce-loop-product__title\">Lodging at RIU Guanacaste<\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">USD $<\/span>165<\/bdi><\/span><\/span>\n <div class=\"cg-amenities\" style=\"font-family: 'Montserrat', sans-serif; color: black; text-transform: capitalize;\"><\/div>\r\n    <div class=\"cg-amenities\">                                <img decoding=\"async\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/05\/Allinclusive.svg\" title=\"todo\" style=\"width:40px; display: inline-block; margin: 0; padding: 0;\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/agenciameridianos.com\/wp-content\/uploads\/2024\/05\/Lodging-Icon.svg\" title=\"hospedaje\" style=\"width:40px; display: inline-block; margin: 0; padding: 0;\">\r\n                        <\/div>\r\n    <\/a><div class=\"woocommerce-loop-product__buttons\"><a class=\"button wpt-custom-view-product-button\" href=\"https:\/\/agenciameridianos.com\/en\/product\/hospedaje-en-riu-guanacaste\/\" data-no-translation=\"\" data-trp-gettext=\"\">Quote<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_17199\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/li>\n<\/ul>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Playas Monta\u00f1a One day tour<\/p>","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-17783","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/pages\/17783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/comments?post=17783"}],"version-history":[{"count":0,"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/pages\/17783\/revisions"}],"wp:attachment":[{"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/media?parent=17783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}