{"id":18106,"date":"2024-05-20T13:38:11","date_gmt":"2024-05-20T13:38:11","guid":{"rendered":"https:\/\/agenciameridianos.com\/web\/?p=18106"},"modified":"2024-06-19T22:34:29","modified_gmt":"2024-06-19T22:34:29","slug":"la-pandemia-el-aprendizaje-de-vivir-las-experiencias","status":"publish","type":"post","link":"https:\/\/agenciameridianos.com\/en\/noticias\/la-pandemia-el-aprendizaje-de-vivir-las-experiencias\/","title":{"rendered":"La pandemia, el aprendizaje de vivir las experiencias"},"content":{"rendered":"<p>El a\u00f1o 2020 trajo para la humanidad algo que ha cambiado nuestra historia, la pandemia del COVID-19. Un virus que lleg\u00f3 inesperadamente y se expandi\u00f3 r\u00e1pidamente causando que muchos planes o metas a futuro cambiaran o incluso se cancelaran. A pesar de los aspectos negativos, sabemos que tambi\u00e9n nos dej\u00f3 ense\u00f1anzas que \u00fanicamente aprendimos gracias a lo que ha sucedido. Hoy, casi tres a\u00f1os despu\u00e9s, queremos rescatarlas, para no recordar esta \u00e9poca s\u00f3lo como un mal momento.<\/p>\n<p>Aprendimos m\u00e1s sobre nosotros mismos. Todos vivimos en condiciones diferentes, pero si hay algo en lo que seguro coincidir\u00edamos es en que fue un periodo de reflexi\u00f3n. Pasar el tiempo fuera de casa y ocupado constantemente hac\u00eda que no te dieses cuenta de muchas cosas, pero con un poco m\u00e1s de tiempo para pensar, conociste nuevas partes de ti. Algunas personas habr\u00e1n cambiado de carrera, otras habr\u00e1n empezado un negocio o adoptado una mascota. Fue, sin duda, un punto clave para muchos.<\/p>\n<p>Tambi\u00e9n empezamos a apreciar las personas y cosas que nos gustan a\u00fan m\u00e1s. Podr\u00edas haber pensado que no te gustaba ir a trabajar, pero en el momento en que te viste atrapado en casa, tal vez lo que m\u00e1s deseabas era ir al trabajo. O bien, no pudiste ver a tus seres queridos por un gran tiempo, haciendo que les echaras mucho en falta. Por eso, sabemos que lo m\u00e1s importante ahora es pasar el rato con esas personas amadas y disfrutar de tus actividades cotidianas.<\/p>\n<p>Sin embargo, no se trata s\u00f3lo de la vida diaria. Muchos habr\u00e1n reflexionado sobre todo lo que no hab\u00edan hecho por siempre postergarlo. Entendimos que la vida es corta e inesperada, y el presente es el \u00fanico momento que tenemos. Este preciso instante es con lo que pod\u00e9s contar\u2026 Cumpl\u00ed esos deseos y metas que postergaste por mucho tiempo: llevar a tus padres a un crucero, viajar a un pa\u00eds tropical con tus amigas o planear un divertido paseo familiar. Todo lo que quer\u00e1s, pero hac\u00e9lo.<\/p>\n<p>Ahora que las fronteras de los pa\u00edses se est\u00e1n comenzando a abrir, lo que m\u00e1s nos emociona es que, por fin, podr\u00e1s cumplir todas esas ideas de viajes que posiblemente tuviste que posponer. Nos encantar\u00eda acompa\u00f1arte en estas nuevas experiencias; despu\u00e9s de pasar tanto tiempo en casa, seguro que pensaste miles de veces en destinos asombrosos que so\u00f1abas visitar. \u00a1Definitivamente es momento de hacerlo!<\/p>\n<p>Los tiempos de crisis siempre son continuados por un ciclo de reflexi\u00f3n, y aprendemos mucho de ellos. Nos hacen replantearnos c\u00f3mo hemos estado viviendo hasta ahora y c\u00f3mo queremos seguir. Te instamos a que hag\u00e1s esta misma reflexi\u00f3n y te lanc\u00e9s a lograr esos sue\u00f1os que a\u00fan no intentaste, con las personas que quer\u00e9s o incluso solo. Si uno de tus sue\u00f1os es viajar, en <strong><u>Meridianos Travel Agency<\/u><\/strong> estaremos felices de compartir contigo esas vivencias emocionantes.<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>El a\u00f1o 2020 trajo para la humanidad algo que ha cambiado nuestra historia, la pandemia del COVID-19. Un virus que lleg\u00f3 inesperadamente y se expandi\u00f3 r\u00e1pidamente causando que muchos planes o metas a futuro cambiaran o incluso se cancelaran. A pesar de los aspectos negativos, sabemos que tambi\u00e9n nos dej\u00f3 ense\u00f1anzas que \u00fanicamente aprendimos gracias [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":18326,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[49],"tags":[],"class_list":["post-18106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/posts\/18106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/comments?post=18106"}],"version-history":[{"count":0,"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/posts\/18106\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/media\/18326"}],"wp:attachment":[{"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/media?parent=18106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/categories?post=18106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/tags?post=18106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}