{"id":18134,"date":"2024-05-20T13:44:42","date_gmt":"2024-05-20T13:44:42","guid":{"rendered":"https:\/\/agenciameridianos.com\/web\/?p=18134"},"modified":"2024-06-19T21:58:59","modified_gmt":"2024-06-19T21:58:59","slug":"envueltos-en-incienso-tierra-santa-y-egipto","status":"publish","type":"post","link":"https:\/\/agenciameridianos.com\/en\/noticias\/envueltos-en-incienso-tierra-santa-y-egipto\/","title":{"rendered":"Envueltos en incienso: Tierra Santa y Egipto"},"content":{"rendered":"<p>\u00bfQu\u00e9 tal si te vas a descubrir un lugar que combina historia, cultura y un aire de misterio? Desde Tierra Santa hasta Egipto: donde el incienso, la historia y la deliciosa gastronom\u00eda est\u00e1n por doquier. Regocijate entre los aires del desierto y las imponentes edificaciones de estos dos destinos. Con Meridianos, vas a tierras lejanas que ocultan tradiciones y maravillas \u00fanicas \u00bfTe apunt\u00e1s?<\/p>\n<p><strong>Caminando en Tierra Santa<\/strong><br \/>\nComenz\u00e1 en uno de los lugares m\u00e1s hist\u00f3ricos y la cuna de m\u00faltiples religiones y s\u00edmbolos: Tierra Santa. La visita a Jerusal\u00e9n es probablemente una de las m\u00e1s esperadas. Admirada como una de las ciudades m\u00e1s llamativas a nivel mundial, esta cuenta con muchas puntos importantes que ten\u00e9s que ver. Podr\u00e1s visitar la V\u00eda Dolorosa, el Barrio Jud\u00edo, el Calvario y el Santo Sepulcro, adem\u00e1s de muchos otros lugares que fueron marcados en la biblia y en la historia. Adem\u00e1s, las emociones se intensifican llegando a El Monte de los Olivos, donde se cree que Jes\u00fas oraba frecuentemente. \u00a1Camin\u00e1 vos mismo por estos hist\u00f3ricos lugares!<\/p>\n<p><strong>Las arenas del tiempo<\/strong><br \/>\nLa curiosidad ser\u00e1 tu mejor compa\u00f1\u00eda al admirar las costumbres y tradiciones que encontr\u00e1s en el Medio Oriente. Egipto tiene tantas maravillas que son dif\u00edciles de contar. Admirar las Pir\u00e1mides de Giza y la Gran Esfinge es esencial para inmortalizar el momento. Este panorama te har\u00e1 sentir como todo un fara\u00f3n. Continu\u00e1 por el Museo Egipcio, la ciudadela de Saladino y la Mezquita de Alabastro, la cual se encuentra bellamente decorada con mosaicos e incrustaciones de piedras preciosas. \u00a1Aqu\u00ed el tiempo se detiene! Este viaje te promete una experiencia completa por el Medio Oriente que no pod\u00e9s perderte.<\/p>\n<p>En Egipto y Tierra Santa, las maravillas se congelaron en el tiempo, pero las emociones contin\u00faan llen\u00e1ndote de mucha aventura. Desde Meridianos, queremos compartir esta experiencia con vos. \u00a1Te estamos esperando para irnos!<\/p>\n<p>Escribinos o llamanos para m\u00e1s informaci\u00f3n. Viv\u00ed Tierra Santa y Egipto con Meridianos.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 tal si te vas a descubrir un lugar que combina historia, cultura y un aire de misterio? Desde Tierra Santa hasta Egipto: donde el incienso, la historia y la deliciosa gastronom\u00eda est\u00e1n por doquier. Regocijate entre los aires del desierto y las imponentes edificaciones de estos dos destinos. Con Meridianos, vas a tierras lejanas [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":18322,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[50,49],"tags":[],"class_list":["post-18134","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/posts\/18134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/comments?post=18134"}],"version-history":[{"count":0,"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/posts\/18134\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/media\/18322"}],"wp:attachment":[{"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/media?parent=18134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/categories?post=18134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/tags?post=18134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}