{"id":21663,"date":"2024-09-11T20:21:29","date_gmt":"2024-09-11T20:21:29","guid":{"rendered":"https:\/\/agenciameridianos.com\/?post_type=product&#038;p=21663"},"modified":"2025-01-22T12:58:54","modified_gmt":"2025-01-22T12:58:54","slug":"luces-de-japon-y-corea","status":"publish","type":"product","link":"https:\/\/agenciameridianos.com\/en\/product\/luces-de-japon-y-corea\/","title":{"rendered":"Japan and Korea lights"},"content":{"rendered":"<p>K-pop and Korean cinema have gained popularity in Japan, while Japanese manga and anime have a large in\ufb02uence in South Korea.<\/p>","protected":false},"excerpt":{"rendered":"<p>K-pop and Korean cinema have gained popularity in Japan, while Japanese manga and anime have a large in\ufb02uence in South Korea.<\/p>","protected":false},"featured_media":17843,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[25,16,17],"product_tag":[18],"class_list":{"0":"post-21663","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-africa-y-asia","7":"product_cat-conoce-el-mundo","8":"product_cat-todos-los-paquetes","9":"product_tag-desde","11":"first","12":"instock","13":"sale","14":"featured","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"acf":{"im_status":"enabled","days_for_delivery":"0","notas_importantes":"\u2022 Cupos limitados\r\n\u2022 Precio garantizado\r\n\u2022 Tarifas no reembolsables\/no transferibles\/no endosables\r\n\u2022 Aplica penalidad por cambios y cancelaciones\r\n\u2022 Alojamiento en habitaci\u00f3n est\u00e1ndar\r\n\u2022 Boletos no reembolsables\/no transferibles\/no endosables \/ Aplica penalidad por cambios\r\n\u2022 El pasajero es responsable de revisar las visas requeridas y que los pasaportes tengan vigencia de m\u00ednimo 6 meses al momento de abordar.\r\n\u2022 Requiere de m\u00ednimo 6 meses al momento de abordar. Requiere llenar formularios migratorios de entradas y salida\r\n\u2022 Veri\ufb01car disposiciones de migraci\u00f3n y de salud en pa\u00eds de destino, las regulaciones y requisitos pueden cambiar en cualquier momento\r\n\u2022 Es importante le env\u00ede a su asesor copia del pasaporte con el cual va a realizar su viaje\r\n\u2022 El paquete de viajes no es reembolsable, no endosable, no transferible y aplica penalidades por cambios"},"_links":{"self":[{"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/product\/21663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/media\/17843"}],"wp:attachment":[{"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/media?parent=21663"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/product_brand?post=21663"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/product_cat?post=21663"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/agenciameridianos.com\/en\/wp-json\/wp\/v2\/product_tag?post=21663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}